{"id":55,"count":0,"description":"","link":"https:\/\/scorpio.servicevision.es\/en\/category\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News archivos - Scorpio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scorpio.servicevision.es\/en\/category\/news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News archivos - Scorpio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scorpio.servicevision.es\/en\/category\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Scorpio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/scorpio.servicevision.es\/en\/category\/news\/\",\"url\":\"https:\/\/scorpio.servicevision.es\/en\/category\/news\/\",\"name\":\"News archivos - Scorpio\",\"isPartOf\":{\"@id\":\"https:\/\/scorpio.servicevision.es\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/scorpio.servicevision.es\/en\/category\/news\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/scorpio.servicevision.es\/en\/category\/news\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/scorpio.servicevision.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/scorpio.servicevision.es\/es\/#website\",\"url\":\"https:\/\/scorpio.servicevision.es\/es\/\",\"name\":\"Scorpio\",\"description\":\"Scorpio, fabricaci\u00f3n y venta de equipos para rodajes cinematogr\u00e1ficos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/scorpio.servicevision.es\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News archivos - Scorpio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scorpio.servicevision.es\/en\/category\/news\/","og_locale":"en_US","og_type":"article","og_title":"News archivos - Scorpio","og_url":"https:\/\/scorpio.servicevision.es\/en\/category\/news\/","og_site_name":"Scorpio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/scorpio.servicevision.es\/en\/category\/news\/","url":"https:\/\/scorpio.servicevision.es\/en\/category\/news\/","name":"News archivos - Scorpio","isPartOf":{"@id":"https:\/\/scorpio.servicevision.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/scorpio.servicevision.es\/en\/category\/news\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/scorpio.servicevision.es\/en\/category\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/scorpio.servicevision.es\/en\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/scorpio.servicevision.es\/es\/#website","url":"https:\/\/scorpio.servicevision.es\/es\/","name":"Scorpio","description":"Scorpio, fabricaci\u00f3n y venta de equipos para rodajes cinematogr\u00e1ficos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scorpio.servicevision.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/scorpio.servicevision.es\/en\/wp-json\/wp\/v2\/categories\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scorpio.servicevision.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/scorpio.servicevision.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/scorpio.servicevision.es\/en\/wp-json\/wp\/v2\/posts?categories=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}